
{"id":470,"date":"2020-06-14T20:26:28","date_gmt":"2020-06-14T20:26:28","guid":{"rendered":"https:\/\/kidsportcanada.ca\/kitchener-waterloo\/?post_type=news_stories&#038;p=470"},"modified":"2020-06-16T15:26:31","modified_gmt":"2020-06-16T15:26:31","slug":"team-kidsport-rebecca-johnston","status":"publish","type":"news_stories","link":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/news-stories\/team-kidsport-rebecca-johnston\/","title":{"rendered":"\u00c9quipe KidSport : Rebecca Johnston"},"content":{"rendered":"<p>Rebecca a grandi dans le monde du hockey avec cinq fr\u00e8res et s\u0153urs tous aussi passionn\u00e9s pour ce sport. Membre de l\u2019\u00e9quipe canadienne de hockey f\u00e9minin depuis 2007, elle est double m\u00e9daill\u00e9e d\u2019or aux Jeux olympiques d\u2019hiver. Elle a notamment aid\u00e9 le Canada \u00e0 r\u00e9colter l\u2019or en sol canadien \u00e0 Vancouver en 2010. Apr\u00e8s avoir obtenu son dipl\u00f4me de l\u2019Universit\u00e9 Cornell, Rebecca a \u00e9t\u00e9 rep\u00each\u00e9e par le Furies de Toronto, de la CWHL, o\u00f9 elle a jou\u00e9 un r\u00f4le d\u00e9terminant pour mener l\u2019\u00e9quipe \u00e0 la coupe Clarkson en 2012-2013.<\/p>\r\n<p>Nouvelle membre d\u2019\u00c9quipe KidSport TM, Rebecca croit fermement \u00e0 notre mission et veut aider les enfants \u00e0 entrer dans le jeu et \u00e0 profiter des bienfaits du sport organis\u00e9.<\/p>","protected":false},"featured_media":468,"template":"","meta":{"_acf_changed":false},"categories":[16],"class_list":["post-470","news_stories","type-news_stories","status-publish","has-post-thumbnail","hentry","category-ambassador"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Team KidSport: Rebecca Johnston - KidSport Kitchener Waterloo<\/title>\n<meta name=\"description\" content=\"Rebecca is a new member of Team KidSport who believes strongly in our mission to get kids off the sidelines and experience the benefits of organized sport.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/news-stories\/team-kidsport-rebecca-johnston\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Team KidSport: Rebecca Johnston - KidSport Kitchener Waterloo\" \/>\n<meta property=\"og:description\" content=\"Rebecca is a new member of Team KidSport who believes strongly in our mission to get kids off the sidelines and experience the benefits of organized sport.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/news-stories\/team-kidsport-rebecca-johnston\/\" \/>\n<meta property=\"og:site_name\" content=\"Kitchener Waterloo\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-16T15:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kidsportcanada.ca\/wp-content\/uploads\/sites\/220\/rebecca-johnston.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/news-stories\\\/team-kidsport-rebecca-johnston\\\/\",\"url\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/news-stories\\\/team-kidsport-rebecca-johnston\\\/\",\"name\":\"Team KidSport: Rebecca Johnston - KidSport Kitchener Waterloo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/news-stories\\\/team-kidsport-rebecca-johnston\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/news-stories\\\/team-kidsport-rebecca-johnston\\\/#primaryimage\"},\"thumbnailUrl\":\"\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/rebecca-johnston.jpg\",\"datePublished\":\"2020-06-14T20:26:28+00:00\",\"dateModified\":\"2020-06-16T15:26:31+00:00\",\"description\":\"Rebecca is a new member of Team KidSport who believes strongly in our mission to get kids off the sidelines and experience the benefits of organized sport.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/news-stories\\\/team-kidsport-rebecca-johnston\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/news-stories\\\/team-kidsport-rebecca-johnston\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/news-stories\\\/team-kidsport-rebecca-johnston\\\/#primaryimage\",\"url\":\"\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/rebecca-johnston.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/sites\\\/220\\\/rebecca-johnston.jpg\",\"width\":1600,\"height\":1000,\"caption\":\"Rebecca Johnston in a hockey uniform while the anthem plays\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/news-stories\\\/team-kidsport-rebecca-johnston\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Team KidSport: Rebecca Johnston\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/#website\",\"url\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/\",\"name\":\"Kitchener Waterloo\",\"description\":\"So all kids can play\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/kitchener-waterloo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Team KidSport: Rebecca Johnston - KidSport Kitchener Waterloo","description":"Nouvelle membre d\u2019\u00c9quipe KidSport TM, Rebecca croit fermement \u00e0 notre mission et veut aider les enfants \u00e0 entrer dans le jeu et \u00e0 profiter des bienfaits du sport organis\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/news-stories\/team-kidsport-rebecca-johnston\/","og_locale":"fr_CA","og_type":"article","og_title":"Team KidSport: Rebecca Johnston - KidSport Kitchener Waterloo","og_description":"Rebecca is a new member of Team KidSport who believes strongly in our mission to get kids off the sidelines and experience the benefits of organized sport.","og_url":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/news-stories\/team-kidsport-rebecca-johnston\/","og_site_name":"Kitchener Waterloo","article_modified_time":"2020-06-16T15:26:31+00:00","og_image":[{"width":1600,"height":1000,"url":"https:\/\/kidsportcanada.ca\/wp-content\/uploads\/sites\/220\/rebecca-johnston.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/news-stories\/team-kidsport-rebecca-johnston\/","url":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/news-stories\/team-kidsport-rebecca-johnston\/","name":"Team KidSport: Rebecca Johnston - KidSport Kitchener Waterloo","isPartOf":{"@id":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/news-stories\/team-kidsport-rebecca-johnston\/#primaryimage"},"image":{"@id":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/news-stories\/team-kidsport-rebecca-johnston\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/sites\/220\/rebecca-johnston.jpg","datePublished":"2020-06-14T20:26:28+00:00","dateModified":"2020-06-16T15:26:31+00:00","description":"Nouvelle membre d\u2019\u00c9quipe KidSport TM, Rebecca croit fermement \u00e0 notre mission et veut aider les enfants \u00e0 entrer dans le jeu et \u00e0 profiter des bienfaits du sport organis\u00e9.","breadcrumb":{"@id":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/news-stories\/team-kidsport-rebecca-johnston\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/news-stories\/team-kidsport-rebecca-johnston\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/news-stories\/team-kidsport-rebecca-johnston\/#primaryimage","url":"\/wp-content\/uploads\/sites\/220\/rebecca-johnston.jpg","contentUrl":"\/wp-content\/uploads\/sites\/220\/rebecca-johnston.jpg","width":1600,"height":1000,"caption":"Rebecca Johnston in a hockey uniform while the anthem plays"},{"@type":"BreadcrumbList","@id":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/news-stories\/team-kidsport-rebecca-johnston\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/"},{"@type":"ListItem","position":2,"name":"Team KidSport: Rebecca Johnston"}]},{"@type":"WebSite","@id":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/#website","url":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/","name":"Kitchener Waterloo","description":"So all kids can play","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/wp-json\/wp\/v2\/news_stories\/470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/wp-json\/wp\/v2\/news_stories"}],"about":[{"href":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/wp-json\/wp\/v2\/types\/news_stories"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/wp-json\/wp\/v2\/media\/468"}],"wp:attachment":[{"href":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/wp-json\/wp\/v2\/media?parent=470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kidsportcanada.ca\/ontario\/kitchener-waterloo\/fr\/wp-json\/wp\/v2\/categories?post=470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}