
{"id":136,"date":"2020-04-01T18:27:16","date_gmt":"2020-04-01T18:27:16","guid":{"rendered":"http:\/\/kidsportcanada.ca\/toronto\/?page_id=136"},"modified":"2021-01-05T16:52:16","modified_gmt":"2021-01-05T16:52:16","slug":"donate","status":"publish","type":"page","link":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/donate\/","title":{"rendered":"Donate"},"content":{"rendered":"<h1>\n\t\tDONATE TODAY\n\t<\/h1>\n<h3>\n\t\tGr\u00e2ce \u00e0 votre soutien, les enfants de Sault Ste. Marie ont l\u2019occasion de se d\u00e9velopper par le sport. La totalit\u00e9 des fonds recueillis \u00e0 Sault Ste. Marie reste \u00e0 Sault Ste. Marie!\n\t<\/h3>\n\t\t\t<a href=\"https:\/\/secure.e2rm.com\/registrant\/startup.aspx?eventid=249761\" target=\"_blank\" role=\"button\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\tDONNER\n\t\t\t<\/a>\n<h2>\n\t\tDONATE Online\n\t<\/h2>\n\t<h3>Donnez \u00e0 SportJeunesse Sault Ste. Marie en utilisant notre formulaire s\u00e9curis\u00e9 en ligne (il s\u2019ouvrira sous un nouvel onglet).<\/h3>\n\t\t\t<a href=\"https:\/\/secure.e2rm.com\/registrant\/startup.aspx?eventid=249761\" target=\"_blank\" role=\"button\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\tDONNER\n\t\t\t<\/a>\n\t\t\t<a href=\"#common-questions\" target=\"_self\" role=\"button\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\tQUESTIONS COURANTES\n\t\t\t\t\t<\/a>\n<h5>\n\t\tPr\u00e9f\u00e9rez-vous donner hors ligne?\n\t<\/h5>\n\t<p>Download and send in the KidSport Donation Form. Our CRA Charitable registration number is             <span class=\"charitablenumber-div\">\n            <span>86212 5986 RR0003<\/span>\n        \n    .<\/p>\n\t\t\t<a href=\"\/wp-content\/uploads\/sites\/109\/kidsport_Ontario_donor_form_2020.pdf\" target=\"_blank\" role=\"button\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\tFORMULAIRE PAPIER\n\t\t\t\t\t<\/a>\n<h2>\n\t\tLe pouvoir du\n\t<\/h2>\n<h2>\n\t\tSport\n\t<\/h2>\n\t<p>Avec votre soutien, SportJeunesse Sault Ste. Marie permet aux enfants d\u2019ici de b\u00e9n\u00e9ficier des avantages du sport toute leur vie durant : ils apprennent le leadership, l\u2019assiduit\u00e9, le d\u00e9vouement et la confiance en soi, et ils adoptent les habitudes et le r\u00e9seau de soutien n\u00e9cessaires pour devenir des adultes en sant\u00e9.<\/p>\n<p>Par le sport, les enfants ont aussi acc\u00e8s au mentorat et \u00e0 l\u2019encadrement de leaders chevronn\u00e9s, ce qui leur permet d\u2019am\u00e9liorer encore plus leurs habilet\u00e9s et de devenir nos futurs leaders communautaires.<\/p>\n<p>Le sport est l\u2019un des meilleurs cadeaux qu\u2019un enfant puisse recevoir. Votre don \u00e0 SportJeunesse Sault Ste. Marie nous aide \u00e0 faire en sorte que TOUS les enfants puissent jouer!<\/p>\n<p>KidSport Sault Ste. Marie gives up to $250 per eligible kid per year, to participate in a season of sport of their choice. Will you give the gift of sport today?<\/p>\n<h2>\n\t\tOTHER WAYS TO Support\n\t<\/h2>\n<h5>\n\t\tDonner une voiture\n\t<\/h5>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/293\/donate_car.svg\" alt=\"A car illustration\" height=\"150\" width=\"150\" title=\"donate_car\" \/>\n\t<p>L\u2019organisme Donate a Car Canada s\u2019occupe de la logistique afin qu\u2019il soit facile pour SportJeunesse Canada de b\u00e9n\u00e9ficier de votre ancienne voiture.<\/p>\n\t\t\t<a href=\"https:\/\/donatecar.ca\/org\/donate.php?charitypage=KidsportCanada\" target=\"_blank\" role=\"button\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\tEN SAVOIR PLUS\n\t\t\t\t\t<\/a>\n<h5>\n\t\tTransfert de valeurs mobili\u00e8res\n\t<\/h5>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/293\/transfer_securities.svg\" alt=\"An illustration of two monetary bills\" height=\"150\" width=\"150\" title=\"transfer_securities\" \/>\n\t<p>En faisant un don d\u2019actions \u00e0 valeur accrue, de fonds communs de placement ou d\u2019options d\u2019achat d\u2019actions, vous ne payez aucun imp\u00f4t sur les gains en capital et vous recevez un re\u00e7u officiel au montant de la juste valeur marchande des valeurs mobili\u00e8res.<\/p>\n\t\t\t<a href=\"\/wp-content\/uploads\/sites\/293\/kidsport_securities_transfer_form_website.pdf\" target=\"_blank\" role=\"button\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\tDEMANDE DE TRANSFERT\n\t\t\t\t\t<\/a>\n<h5>\n\t\tDon planifi\u00e9\n\t<\/h5>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/293\/planned_giving.svg\" alt=\"An illustration of a present with a bow on the top\" height=\"150\" width=\"150\" title=\"planned_giving\" \/>\n\t<p>Les legs testamentaires ne sont pas r\u00e9serv\u00e9s aux ultra-riches : n\u2019importe qui peut r\u00e9duire le fardeau fiscal de sa famille en pr\u00e9voyant un don \u00e0 SportJeunesse dans son testament.<\/p>\n\t\t\t<a href=\"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/contact-us\/\" target=\"_self\" role=\"button\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\tCONTACTEZ-NOUS\n\t\t\t\t\t<\/a>\n<h5>\n\t\tDevenir un partenaire\n\t<\/h5>\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/wp-content\/uploads\/sites\/293\/become_partner.svg\" alt=\"A participation ribbon with a heart on it\" height=\"150\" width=\"150\" title=\"become_partner\" \/>\n\t<p>SportJeunesse est un organisme caritatif communautaire et les entreprises locales sont essentielles \u00e0 sa mission. Aidez notre communaut\u00e9 \u00e0 devenir plus forte en vous associant \u00e0 SportJeunesse d\u00e8s maintenant!<\/p>\n\t\t\t<a href=\"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/contact-us\/\" target=\"_self\" role=\"button\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\tEN SAVOIR PLUS\n\t\t\t\t\t<\/a>\n<h2>\n\t\tCOMMON Questions\n\t<\/h2>\n\t\t\t<a href=\"#\" id=\"fl-accordion--label-0\">Mon don est-il s\u00e9curis\u00e9?<\/a>\n\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-0\"><i>Expand<\/i><\/a>\n\t\t<p>Oui. Les dons faits \u00e0 SportJeunesse sont trait\u00e9s par FrontStream, l\u2019une des plus importantes plateformes nationales de collecte de fonds. Vos donn\u00e9es de carte de cr\u00e9dit sont s\u00e9curis\u00e9es et jamais nous ne vendrons ni ne divulguerons vos renseignements personnels.<\/p>\n\t\t\t<a href=\"#\" id=\"fl-accordion--label-1\">Mon don est-il d\u00e9ductible du revenu imposable?<\/a>\n\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-1\"><i>Expand<\/i><\/a>\n\t\t<p>Oui, SportJeunesse d\u00e9livre un re\u00e7u officiel pour les dons admissibles de plus de 20 $. Donnez en ligne pour recevoir un re\u00e7u automatiquement et sauver un arbre! Les re\u00e7us pour dons faits hors ligne sont d\u00e9livr\u00e9s avant la fin du trimestre suivant.<\/p>\n\t\t\t<a href=\"#\" id=\"fl-accordion--label-2\">Puis-je faire un don mensuel r\u00e9current?<\/a>\n\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-2\"><i>Expand<\/i><\/a>\n\t\t<p>You sure can! Monthly donors sustain our organization by providing reliable funding &#8211; and a big impact! Just $25 a month adds up to help a kid in one year.<\/p>\n<p>Simply select \u201cMonthly Gift\u201d at the top of our online donation form, or check the \u201cMonthly Gift\u201d box on the paper donation form. Your monthly donation will show up on your credit card statement, on the same date and for the same amount as your first gift.<\/p>\n\t\t\t<a href=\"#\" id=\"fl-accordion--label-3\">\u00c0 quoi sert mon don?<\/a>\n\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-3\"><i>Expand<\/i><\/a>\n\t\t<p>Chaque don fait \u00e0 SportJeunesse permet aux enfants de quitter la ligne lat\u00e9rale pour pratiquer un sport pendant une saison. Jusqu\u2019\u00e0 20 % de votre don pourrait servir \u00e0 couvrir nos frais de fonctionnement, par exemple pour organiser des collectes de fonds, remplacer l\u2019encre de notre imprimante ou remercier nos b\u00e9n\u00e9voles en leur offrant un repas ou une tasse de caf\u00e9. Le reste de votre don \u2013 de 80 \u00e0 100 % \u2013 est distribu\u00e9 sous forme de subventions pour payer les frais d\u2019inscription des enfants de chez nous.<\/p>\n\t\t\t<a href=\"#\" id=\"fl-accordion--label-4\">\u00c0 qui dois-je adresser mes questions?<\/a>\n\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-4\"><i>Expand<\/i><\/a>\n\t\t<p>N\u2019h\u00e9sitez pas \u00e0 communiquer avec les b\u00e9n\u00e9voles de SportJeunesse Sault Ste. Marie : nous sommes toujours heureux d\u2019aider.<\/p>\n<p>Please get in touch via email at             <span class=\"emailaddress-div\">\n            <a href=\"mailto:saultstemarie@kidsportontario.ca\">saultstemarie@kidsportontario.ca<\/a>\n             or call             <span class=\"phonenumber-div\">\n            <a href=\"tel:416-899-9106\">416-899-9106<\/a>\n            .<\/p>\n\t\t\t<a href=\"#\" id=\"fl-accordion--label-5\">Mon don restera-t-il dans une communaut\u00e9 en particulier?<\/a>\n\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-5\"><i>Expand<\/i><\/a>\n\t\t<p>Oui! Les dons faits \u00e0 une section communautaire comme SportJeunesse Sault Ste. Marie resteront toujours ici pour aider les enfants qui habitent ici. Si votre communaut\u00e9 de choix n\u2019a pas de section communautaire, ou si vous souhaitez faire rayonner votre don sur un territoire un peu plus grand, veuillez envisager de faire un don au fonds provincial de SportJeunesse Sault Ste. Marie, qui fournit des subventions et de l\u2019aide aux enfants qui habitent dans des localit\u00e9s sans section locale de SportJeunesse.<\/p>\n\t\t\t<a href=\"#\" id=\"fl-accordion--label-6\">I\u2019d like to fundraise for KidSport &#8211; how can I get started?<\/a>\n\t\t\t\t\t\t\t<a href=\"#\" id=\"fl-accordion--icon-6\"><i>Expand<\/i><\/a>\n\t\t<p>We\u2019re ready to team up with you on whatever fundraising ideas you have! Please reach out by emailing             <span class=\"emailaddress-div\">\n            <a href=\"mailto:saultstemarie@kidsportontario.ca\">saultstemarie@kidsportontario.ca<\/a>\n             with a quick description of your fundraising interests and we\u2019ll get back to you right away.<\/p>\n<h2>\n\t\tLe coin de ambassadeur<br>Brett Levis\n\t<\/h2>\n<h3>\n\t\tVoyez les raisons pour lesquelles Brett Levis, joueur des Whitecaps de Vancouver, appuie SportJeunesse.\n\t<\/h3>\n\t\t\t<a href=\"\/ontario\/sault-ste-marie\/fr\/void(0)\/\" target=\"_self\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\tREGARDER LE FILM\n\t\t<\/a>\n\t\t\t<a href=\"\/ontario\/sault-ste-marie\/fr\/void(0)\/\" target=\"_self\" rel=\"noopener noreferrer\">\n\t\t\t\t\t\t\t\t\t\t\tREGARDER LE FILM\n\t\t<\/a>","protected":false},"excerpt":{"rendered":"<p>DONATE TODAY Your support provides kids from Sault Ste. Marie with the opportunity to grow through sport. 100% of funds raised in KidSport Sault Ste. Marie stay in Sault Ste. Marie! DONATE NOW DONATE Online Donate to KidSport Sault Ste. Marie using our secure online form (will open in a new tab). DONATE NOW COMMON&hellip;<\/p>","protected":false},"author":10,"featured_media":192,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-136","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Donate - KidSport Sault Ste. Marie<\/title>\n<meta name=\"description\" content=\"Your financial support provides kids with the opportunity to grow through sport. Donate to kidSport securely online or by mail.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/donate\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donate - KidSport Sault Ste. Marie\" \/>\n<meta property=\"og:description\" content=\"Your financial support provides kids with the opportunity to grow through sport. Donate to kidSport securely online or by mail.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/donate\/\" \/>\n<meta property=\"og:site_name\" content=\"Sault Ste. Marie\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-05T16:52:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kidsportcanada.ca\/wp-content\/uploads\/sites\/293\/donate-today-headline.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/donate\\\/\",\"url\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/donate\\\/\",\"name\":\"Donate - KidSport Sault Ste. Marie\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/donate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/donate\\\/#primaryimage\"},\"thumbnailUrl\":\"\\\/wp-content\\\/uploads\\\/sites\\\/293\\\/donate-today-headline.jpg\",\"datePublished\":\"2020-04-01T18:27:16+00:00\",\"dateModified\":\"2021-01-05T16:52:16+00:00\",\"description\":\"Your financial support provides kids with the opportunity to grow through sport. Donate to kidSport securely online or by mail.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/donate\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/donate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/donate\\\/#primaryimage\",\"url\":\"\\\/wp-content\\\/uploads\\\/sites\\\/293\\\/donate-today-headline.jpg\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/sites\\\/293\\\/donate-today-headline.jpg\",\"width\":1600,\"height\":1000,\"caption\":\"An outdoor hockey rink with a red goalie net\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/donate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/#website\",\"url\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/\",\"name\":\"Sault Ste. Marie\",\"description\":\"So all kids can play\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kidsportcanada.ca\\\/ontario\\\/sault-ste-marie\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Donate - KidSport Sault Ste. Marie","description":"Gr\u00e2ce \u00e0 votre soutien, les enfants ont l\u2019occasion de se d\u00e9velopper par le sport.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/donate\/","og_locale":"fr_CA","og_type":"article","og_title":"Donate - KidSport Sault Ste. Marie","og_description":"Your financial support provides kids with the opportunity to grow through sport. Donate to kidSport securely online or by mail.","og_url":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/donate\/","og_site_name":"Sault Ste. Marie","article_modified_time":"2021-01-05T16:52:16+00:00","og_image":[{"width":1600,"height":1000,"url":"https:\/\/kidsportcanada.ca\/wp-content\/uploads\/sites\/293\/donate-today-headline.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimation du temps de lecture":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/donate\/","url":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/donate\/","name":"Donate - KidSport Sault Ste. Marie","isPartOf":{"@id":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/donate\/#primaryimage"},"image":{"@id":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/donate\/#primaryimage"},"thumbnailUrl":"\/wp-content\/uploads\/sites\/293\/donate-today-headline.jpg","datePublished":"2020-04-01T18:27:16+00:00","dateModified":"2021-01-05T16:52:16+00:00","description":"Gr\u00e2ce \u00e0 votre soutien, les enfants ont l\u2019occasion de se d\u00e9velopper par le sport.","breadcrumb":{"@id":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/donate\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/donate\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/donate\/#primaryimage","url":"\/wp-content\/uploads\/sites\/293\/donate-today-headline.jpg","contentUrl":"\/wp-content\/uploads\/sites\/293\/donate-today-headline.jpg","width":1600,"height":1000,"caption":"An outdoor hockey rink with a red goalie net"},{"@type":"BreadcrumbList","@id":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/donate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/"},{"@type":"ListItem","position":2,"name":"Donate"}]},{"@type":"WebSite","@id":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/#website","url":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/","name":"Sault Ste. Marie","description":"So all kids can play","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"}]}},"_links":{"self":[{"href":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/wp-json\/wp\/v2\/pages\/136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/wp-json\/wp\/v2\/comments?post=136"}],"version-history":[{"count":0,"href":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/wp-json\/wp\/v2\/pages\/136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/wp-json\/wp\/v2\/media\/192"}],"wp:attachment":[{"href":"https:\/\/kidsportcanada.ca\/ontario\/sault-ste-marie\/fr\/wp-json\/wp\/v2\/media?parent=136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}